{"id":4375,"date":"2023-03-15T00:01:45","date_gmt":"2023-03-14T23:01:45","guid":{"rendered":"http:\/\/travelsmartcampaign.org\/?post_type=library&#038;p=4375"},"modified":"2023-03-15T10:27:10","modified_gmt":"2023-03-15T09:27:10","slug":"85-der-globalen-unternehmen-haben-keine-glaubwurdigen-plane-zur-reduzierung-der-flugemissionen","status":"publish","type":"library","link":"https:\/\/travelsmartcampaign.org\/de\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/","title":{"rendered":"85% der globalen Unternehmen haben keine glaubw\u00fcrdigen Pl\u00e4ne zur Reduzierung der Flugemissionen ihrer Unternehmen"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">85% der weltweiten Unternehmen setzen sich keine ehrgeizigen Ziele, um die Emissionen von Gesch\u00e4ftsreisen zu reduzieren, so die zweite Ausgabe eines Rankings \u00fcber Gesch\u00e4ftsreisen der Travel Smart-Kampagne.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nur 50 von 322 Unternehmen haben sich Ziele zur Verringerung der Emissionen von Gesch\u00e4ftsreisen gesetzt. Von den Unternehmen, die sich Ziele gesetzt haben, erf\u00fcllen nur vier Unternehmen den \"Goldstandard\", d. h. sie berichten \u00fcber die Emissionen von Flugreisen und verpflichten sich, diese bis 2025 oder fr\u00fcher um 50% oder mehr zu reduzieren. Diese sind Novo Nordisk (Pharmazeutische Industrie, D\u00e4nemark), Swiss Re (Finanzwesen, Schweiz), Fidelity International (Finanzwesen, Vereinigtes K\u00f6nigreich) und <\/span><span style=\"font-weight: 400;\">ABN Amro (Finanzen, Niederlande).<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-6454\" src=\"http:\/\/travelsmartcampaign.org\/wp-content\/uploads\/Original_Infographic-2-Ranking-card-for-companies-5-1024x576.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/Original_Infographic-2-Ranking-card-for-companies-5-1024x576.png 1024w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/Original_Infographic-2-Ranking-card-for-companies-5-300x169.png 300w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/Original_Infographic-2-Ranking-card-for-companies-5-768x432.png 768w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/Original_Infographic-2-Ranking-card-for-companies-5-1536x864.png 1536w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/Original_Infographic-2-Ranking-card-for-companies-5-18x10.png 18w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/Original_Infographic-2-Ranking-card-for-companies-5.png 1920w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Der erste \u00dcberblick \u00fcber die Berichterstattung \u00fcber Nicht-CO2-Emissionen im Zusammenhang mit Gesch\u00e4ftsfl\u00fcgen zeigt, dass 40 Unternehmen mit der Berichterstattung \u00fcber alle mit Gesch\u00e4ftsfl\u00fcgen verbundenen Treibhausgasemissionen eine Vorreiterrolle einnehmen. Die Pharmariesen AstraZeneca und Pfizer sowie die Beratungsunternehmen Boston Consulting Group und Deloitte gehen mit gutem Beispiel voran und ber\u00fccksichtigen in ihrer Berichterstattung die gesamten Auswirkungen des Fliegens.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die Klimaauswirkungen des Gesch\u00e4ftsflugverkehrs gehen \u00fcber die CO2-Emissionen hinaus. Neben CO2 sto\u00dfen die Flugzeugtriebwerke auch andere Gase - Stickoxide, Schwefeldioxid und Wasser - sowie Feinstaub (Ru\u00df) aus.  Diese werden gemeinhin als Nicht-CO2-Emissionen bezeichnet, und es ist <\/span><a href=\"https:\/\/www.easa.europa.eu\/en\/document-library\/research-reports\/report-commission-european-parliament-and-council\"><span style=\"font-weight: 400;\">gesch\u00e4tzt <\/span><\/a><span style=\"font-weight: 400;\">dass sie f\u00fcr zwei Drittel der gesamten Klimaerw\u00e4rmung durch Flugreisen verantwortlich sind. Doch nur sehr wenige Unternehmen ber\u00fccksichtigen die Gesamtauswirkungen von Gesch\u00e4ftsfl\u00fcgen, indem sie auch die Nicht-CO2-Effekte ber\u00fccksichtigen.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Denise Auclair, Corporate Travel Manager bei Transport &amp; Environment, sagte:<\/span><i><span style=\"font-weight: 400;\"> \"Die Unternehmen verschlie\u00dfen die Augen vor den Sch\u00e4den, die das Fliegen f\u00fcr die Arbeit mit sich bringt. Die meisten Unternehmen ergreifen wenig bis gar keine Ma\u00dfnahmen in Bezug auf Gesch\u00e4ftsfl\u00fcge, was alle anderen Reiseziele im Zusammenhang mit der Bek\u00e4mpfung des Klimawandels bedeutungslos werden l\u00e4sst. Nur wenige Vorreiter orientieren sich an der Wissenschaft, indem sie die Nicht-CO2-Emissionen ausweisen - den verborgenen Teil des Eisbergs, der den gesamten Einfluss des Luftverkehrs auf das Klima ausmacht.<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Volkswagen, KPMG und Johnson &amp; Johnson sind die drei gr\u00f6\u00dften Emittenten<\/span><span style=\"font-weight: 400;\"> des Travel Smart-Rankings ohne Zielvorgabe f\u00fcr die Verringerung ihrer Reiseemissionen (1). Die Festlegung solcher Ziele ist jedoch m\u00f6glich und notwendig, da Unternehmen \u00e4hnlicher Gr\u00f6\u00dfe und Branche wie McKinsey, Deloitte und AstraZeneca dies bereits getan haben.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die Studie zeigt, dass 101 Milliarden Unternehmen \u2013 die gr\u00f6\u00dften Emittenten im Ranking \u2013, wenn sie sich Reduktionsziele von 501 Milliarden Tonnen setzen w\u00fcrden, dies bereits die H\u00e4lfte des Weges zur Erreichung des globalen Ziels von -501 Milliarden Tonnen Emissionen aus dem Flugverkehr bis 2025 bedeuten w\u00fcrde. Die Reduzierung der Emissionen aus dem Flugverkehr ist heute wichtiger denn je, wenn wir die Erderw\u00e4rmung auf 1,5 \u00b0C begrenzen wollen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Im entscheidenden Jahrzehnt bis 2030 lassen sich die Emissionen des Luftverkehrs am besten senken, indem man weniger fliegt. Denn der Zeitpunkt f\u00fcr die Einf\u00fchrung nachhaltiger Kraftstoffe und emissionsfreier Flugzeuge liegt derzeit erst nach 2030, und ein Ausgleich der Emissionen kann die Reduzierung der Emissionen nicht ersetzen.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die Travel Smart-Kampagne ruft Unternehmen dazu auf, sich ehrgeizige Ziele zu setzen, um die Emissionen von Gesch\u00e4ftsreisen zu reduzieren, wenn m\u00f6glich vom Flugzeug auf die Bahn umzusteigen und Videokonferenzen als Ersatz f\u00fcr Langstreckenfl\u00fcge zu bevorzugen.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Denise Auclair fasst zusammen: \u201e<\/span><i><span style=\"font-weight: 400;\">Die gr\u00f6\u00dften Emittenten m\u00fcssen eine \u00fcberproportionale Rolle bei der Verringerung ihrer Emissionen aus Gesch\u00e4ftsfl\u00fcgen spielen. Die Mittel, um dies zu erreichen, sind leichter zug\u00e4nglich als je zuvor: Bahnreisen, wenn die Entfernungen es zulassen, und Videokonferenzen, um Langstreckenfl\u00fcge zu vermeiden.<\/span><\/i><\/p>\n<p><b>Hinweis f\u00fcr Redakteure:\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Transport &amp; Environment startete 2022 gemeinsam mit einer Koalition globaler Partner die Kampagne Travel Smart mit einer j\u00e4hrlichen Ausgabe eines Unternehmensrankings zu nachhaltigen Gesch\u00e4ftsreisepraktiken. Die Kampagne richtet sich an Unternehmen mit dem Ziel, ihre Emissionen durch Gesch\u00e4ftsreisen bis 2025 oder fr\u00fcher um 50% oder mehr des Vor-Covid-Niveaus zu reduzieren.\u200b<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Das Travel Smart-Ranking bewertet 322 US-amerikanische, europ\u00e4ische und indische Unternehmen anhand von 10 Indikatoren in Bezug auf Flugreiseemissionen, Reduktionsziele und Berichterstattung. Die Top-Flugg\u00e4ste aus den 17 L\u00e4ndern des Rankings repr\u00e4sentieren einen betr\u00e4chtlichen Anteil der Gesch\u00e4ftsreisen weltweit. Die Analyse wirft Licht auf die erheblichen Anstrengungen, die einige globale Unternehmen noch unternehmen m\u00fcssen, um ihre Gesch\u00e4ftsreiseemissionen zu reduzieren. Unternehmen werden mit den Noten A, B, C oder D bewertet. In der diesj\u00e4hrigen Ausgabe des Rankings qualifizierten sich 11 Unternehmen f\u00fcr die Note A, 38 f\u00fcr die Note B, w\u00e4hrend die \u00fcberwiegende Mehrheit die Note C (212) erhielt und 61 Unternehmen die Note D neben ihrem Namen sahen.\u00a0<\/span><\/p>\n<p>(1) <span style=\"font-weight: 400;\">Laut Emissionsbericht 2019<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Die gr\u00f6\u00dften Unternehmen der Welt vers\u00e4umen es, sich Ziele f\u00fcr die klimasch\u00e4dlichste Form der Gesch\u00e4ftsreise - den Flugverkehr - zu setzen.<\/p>","protected":false},"featured_media":3122,"template":"","topic":[],"visibility":[],"post-country":[26],"language":[27],"category-post-type":[28],"class_list":["post-4375","library","type-library","status-publish","has-post-thumbnail","hentry","post-country-global","language-english","category-post-type-press-release"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>85% of global companies don\u2019t have credible plans to reduce corporate flying emissions - Travel Smart Campaign<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelsmartcampaign.org\/de\/bibliothek\/85-der-globalen-unternehmen-haben-keine-glaubwurdigen-plane-zur-reduzierung-der-flugemissionen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"85% of global companies don\u2019t have credible plans to reduce corporate flying emissions - Travel Smart Campaign\" \/>\n<meta property=\"og:description\" content=\"World\u2019s largest companies fail to set targets on most climate intensive form of business travel - air travel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelsmartcampaign.org\/de\/bibliothek\/85-der-globalen-unternehmen-haben-keine-glaubwurdigen-plane-zur-reduzierung-der-flugemissionen\/\" \/>\n<meta property=\"og:site_name\" content=\"Travel Smart Campaign\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-15T09:27:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/airplane-image-travel-smart-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/\",\"name\":\"85% of global companies don\u2019t have credible plans to reduce corporate flying emissions - Travel Smart Campaign\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/airplane-image-travel-smart-1-scaled.jpg\",\"datePublished\":\"2023-03-14T23:01:45+00:00\",\"dateModified\":\"2023-03-15T09:27:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/airplane-image-travel-smart-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/airplane-image-travel-smart-1-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"airplane image\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"85% of global companies don\u2019t have credible plans to reduce corporate flying emissions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#website\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\",\"name\":\"Travel Smart\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/travelsmartcampaign.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#organization\",\"name\":\"Travel Smart\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/travel-smart-min.jpeg\",\"contentUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/travel-smart-min.jpeg\",\"width\":1200,\"height\":690,\"caption\":\"Travel Smart\"},\"image\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"85% der globalen Unternehmen haben keine glaubw\u00fcrdigen Pl\u00e4ne zur Reduzierung der Emissionen durch Flugreisen \u2013 Travel Smart-Kampagne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelsmartcampaign.org\/de\/bibliothek\/85-der-globalen-unternehmen-haben-keine-glaubwurdigen-plane-zur-reduzierung-der-flugemissionen\/","og_locale":"de_DE","og_type":"article","og_title":"85% of global companies don\u2019t have credible plans to reduce corporate flying emissions - Travel Smart Campaign","og_description":"World\u2019s largest companies fail to set targets on most climate intensive form of business travel - air travel.","og_url":"https:\/\/travelsmartcampaign.org\/de\/bibliothek\/85-der-globalen-unternehmen-haben-keine-glaubwurdigen-plane-zur-reduzierung-der-flugemissionen\/","og_site_name":"Travel Smart Campaign","article_modified_time":"2023-03-15T09:27:10+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/airplane-image-travel-smart-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/","url":"https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/","name":"85% der globalen Unternehmen haben keine glaubw\u00fcrdigen Pl\u00e4ne zur Reduzierung der Emissionen durch Flugreisen \u2013 Travel Smart-Kampagne","isPartOf":{"@id":"https:\/\/travelsmartcampaign.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/#primaryimage"},"image":{"@id":"https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/#primaryimage"},"thumbnailUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/airplane-image-travel-smart-1-scaled.jpg","datePublished":"2023-03-14T23:01:45+00:00","dateModified":"2023-03-15T09:27:10+00:00","breadcrumb":{"@id":"https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/#primaryimage","url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/airplane-image-travel-smart-1-scaled.jpg","contentUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/airplane-image-travel-smart-1-scaled.jpg","width":2560,"height":1707,"caption":"airplane image"},{"@type":"BreadcrumbList","@id":"https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/travelsmartcampaign.org\/"},{"@type":"ListItem","position":2,"name":"85% of global companies don\u2019t have credible plans to reduce corporate flying emissions"}]},{"@type":"WebSite","@id":"https:\/\/travelsmartcampaign.org\/#website","url":"https:\/\/travelsmartcampaign.org\/","name":"Travel Smart","description":"","publisher":{"@id":"https:\/\/travelsmartcampaign.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelsmartcampaign.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/travelsmartcampaign.org\/#organization","name":"Travel Smart","url":"https:\/\/travelsmartcampaign.org\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/travelsmartcampaign.org\/#\/schema\/logo\/image\/","url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/travel-smart-min.jpeg","contentUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/travel-smart-min.jpeg","width":1200,"height":690,"caption":"Travel Smart"},"image":{"@id":"https:\/\/travelsmartcampaign.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/library\/4375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/library"}],"about":[{"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/types\/library"}],"version-history":[{"count":0,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/library\/4375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/media\/3122"}],"wp:attachment":[{"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/media?parent=4375"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/topic?post=4375"},{"taxonomy":"visibility","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/visibility?post=4375"},{"taxonomy":"post-country","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/post-country?post=4375"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/language?post=4375"},{"taxonomy":"category-post-type","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/category-post-type?post=4375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}