{"id":8999,"date":"2023-07-04T15:31:18","date_gmt":"2023-07-04T14:31:18","guid":{"rendered":"http:\/\/travelsmartcampaign.org\/?post_type=library&#038;p=8999"},"modified":"2024-12-16T18:03:55","modified_gmt":"2024-12-16T17:03:55","slug":"umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen","status":"publish","type":"library","link":"https:\/\/travelsmartcampaign.org\/de\/library\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\/","title":{"rendered":"Umfrage zeigt: Die Mehrheit der Mitarbeitenden in Schweizer Unternehmen wird weniger fliegen"},"content":{"rendered":"<p><b>Insgesamt fordert eine neue Umfrage im Auftrag des Dachverbands \u00abTransport &amp; Environment T&amp;E\u00bb drei Viertel der Mitarbeitenden in gr\u00f6sseren Schweizer Unternehmen weniger Gesch\u00e4ftsfl\u00fcge, um die Umwelt zu schonen. Der VCS Verkehrs-Club der Schweiz f\u00fchlt sich in seinen Bem\u00fchungen best\u00e4tigt: Die Reduktion der Gesch\u00e4ftsfl\u00fcge ist eine wirksame und einfache M\u00f6glichkeit, die CO2-Emissionen zu senken und damit das Schweizer Netto-Null-Ziel bis 2050 zu erreichen.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Die Umfrage hat ergeben, dass nach wie vor fast zwei Drittel der Angestellten in gr\u00f6sseren Unternehmen gesch\u00e4ftlich fliegen. Die Tendenz ist jedoch r\u00fcckl\u00e4ufig: Von den Gesch\u00e4ftsreisenden wird erwartet, dass sie seit der COVID-Pandemie weniger fliegen. Eine weitere Erkenntnis: Drei Viertel der Befragten sind der Meinung, dass eine Reduktion von Gesch\u00e4ftsfl\u00fcgen ein wichtiger Faktor f\u00fcr die Verbesserung der CO2-Bilanz des Unternehmens ist. Ferner fordern die Befragten, dass sich ihr Unternehmen diesbez\u00fcglich Ziele setzen sollte.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Yves Chatton, VCS-Projektleiter Verkehrspolitik sieht sich best\u00e4tigt: \u201eDie Umfrage zeigt eindeutig: Die Angestellten wollen weniger Gesch\u00e4ftsfl\u00fcge unternehmen. Die Unternehmen m\u00fcssen auf diese Erwartung reagieren und Reduktionsziele festlegen. Die Pandemie hat gezeigt, dass Unternehmen genauso effizient sein k\u00f6nnen, wenn sie weniger fliegen. Dies ist sowohl f\u00fcr den Klimaschutz als auch f\u00fcr die Lebensqualit\u00e4t der Belegschaft von Vorteil.\u00bb<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die T&amp;E-Umfrage wurde im Rahmen der internationalen Travel Smart-Kampagne durchgef\u00fchrt. <\/span><span style=\"font-weight: 400;\">Die Meinungen der Schweizer Angestellten stimmen mit jenen der Meinungen in anderen europ\u00e4ischen L\u00e4ndern \u00fcberein.<\/span><span style=\"font-weight: 400;\"> Die Travel Smart-Kampagne fordert von den Unternehmen ein klares Bekenntnis, Gesch\u00e4ftsfl\u00fcge bis sp\u00e4testens 2025 im Vergleich zu 2019 um mindestens 50% zu reduzieren. Anschlie\u00dfend soll die Reduzierung der Emissionen regelm\u00e4\u00dfig in einem Bericht ver\u00f6ffentlicht werden.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Im Rahmen der T&amp;E-Umfrage wurden 500 Angestellte aus Schweizer Unternehmen mit mindestens 50 Mitarbeitenden vom Forschungsdienst Ipsos befragt. Die vollst\u00e4ndigen Ergebnisse der Umfrage k\u00f6nnen <\/span><span style=\"font-weight: 400;\">hier<\/span><span style=\"font-weight: 400;\"> Weitere werden.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Kontakt:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Yves Chatton, Projektleiter Verkehrspolitik, 031 328 58 64 <\/span><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Gem\u00e4ss einer neuen Umfrage im Auftrag des Dachverbands \u00abTransport &amp; Environment T&amp;E\u00bb fordern 3\/4 der Mitarbeitenden in gr\u00f6sseren Schweizer Unternehmen weniger Gesch\u00e4ftsfl\u00fcge, um die Umwelt zu schonen. Der VCS Verkehrs-Club der Schweiz f\u00fchlt sich in seinen Anstrengungen best\u00e4tigt: die Reduktion der Gesch\u00e4ftsfl\u00fcge ist eine wirksame und einfache M\u00f6glichkeit, die CO2-Emissionen zu senken und damit das [&hellip;]<\/p>\n","protected":false},"featured_media":8943,"template":"","topic":[],"visibility":[55],"post-country":[36],"language":[39],"category-post-type":[232],"class_list":["post-8999","library","type-library","status-publish","has-post-thumbnail","hentry","visibility-open","post-country-switzerland","language-german","category-post-type-survey"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Umfrage zeigt: Mehrheit der Mitarbeitenden in Schweizer Unternehmen will weniger fliegen - Travel Smart Campaign<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelsmartcampaign.org\/de\/bibliothek\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Umfrage zeigt: Mehrheit der Mitarbeitenden in Schweizer Unternehmen will weniger fliegen - Travel Smart Campaign\" \/>\n<meta property=\"og:description\" content=\"Gem\u00e4ss einer neuen Umfrage im Auftrag des Dachverbands \u00abTransport &amp; Environment T&amp;E\u00bb fordern 3\/4 der Mitarbeitenden in gr\u00f6sseren Schweizer Unternehmen weniger Gesch\u00e4ftsfl\u00fcge, um die Umwelt zu schonen. Der VCS Verkehrs-Club der Schweiz f\u00fchlt sich in seinen Anstrengungen best\u00e4tigt: die Reduktion der Gesch\u00e4ftsfl\u00fcge ist eine wirksame und einfache M\u00f6glichkeit, die CO2-Emissionen zu senken und damit das [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelsmartcampaign.org\/de\/bibliothek\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\/\" \/>\n<meta property=\"og:site_name\" content=\"Travel Smart Campaign\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-16T17:03:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/AdobeStock_381933401-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1621\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\\\/\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\\\/\",\"name\":\"Umfrage zeigt: Mehrheit der Mitarbeitenden in Schweizer Unternehmen will weniger fliegen - Travel Smart Campaign\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/AdobeStock_381933401-scaled.jpeg\",\"datePublished\":\"2023-07-04T14:31:18+00:00\",\"dateModified\":\"2024-12-16T17:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/AdobeStock_381933401-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/AdobeStock_381933401-scaled.jpeg\",\"width\":2560,\"height\":1621,\"caption\":\"Side view of positive ethnic female in casual outfit with smartphone working on laptop and smiling while resting on comfortable armchair near window of train\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Umfrage zeigt: Mehrheit der Mitarbeitenden in Schweizer Unternehmen will weniger fliegen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#website\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\",\"name\":\"Travel Smart\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/travelsmartcampaign.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#organization\",\"name\":\"Travel Smart\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/travel-smart-min.jpeg\",\"contentUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/travel-smart-min.jpeg\",\"width\":1200,\"height\":690,\"caption\":\"Travel Smart\"},\"image\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Umfrage zeigt: Mehrheit der Mitarbeitenden in Schweizer Unternehmen will weniger fliegen \u2013 Travel Smart-Kampagne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelsmartcampaign.org\/de\/bibliothek\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\/","og_locale":"de_DE","og_type":"article","og_title":"Umfrage zeigt: Mehrheit der Mitarbeitenden in Schweizer Unternehmen will weniger fliegen - Travel Smart Campaign","og_description":"Gem\u00e4ss einer neuen Umfrage im Auftrag des Dachverbands \u00abTransport &amp; Environment T&amp;E\u00bb fordern 3\/4 der Mitarbeitenden in gr\u00f6sseren Schweizer Unternehmen weniger Gesch\u00e4ftsfl\u00fcge, um die Umwelt zu schonen. Der VCS Verkehrs-Club der Schweiz f\u00fchlt sich in seinen Anstrengungen best\u00e4tigt: die Reduktion der Gesch\u00e4ftsfl\u00fcge ist eine wirksame und einfache M\u00f6glichkeit, die CO2-Emissionen zu senken und damit das [&hellip;]","og_url":"https:\/\/travelsmartcampaign.org\/de\/bibliothek\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\/","og_site_name":"Travel Smart Campaign","article_modified_time":"2024-12-16T17:03:55+00:00","og_image":[{"width":2560,"height":1621,"url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/AdobeStock_381933401-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelsmartcampaign.org\/library\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\/","url":"https:\/\/travelsmartcampaign.org\/library\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\/","name":"Umfrage zeigt: Mehrheit der Mitarbeitenden in Schweizer Unternehmen will weniger fliegen \u2013 Travel Smart-Kampagne","isPartOf":{"@id":"https:\/\/travelsmartcampaign.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelsmartcampaign.org\/library\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\/#primaryimage"},"image":{"@id":"https:\/\/travelsmartcampaign.org\/library\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\/#primaryimage"},"thumbnailUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/AdobeStock_381933401-scaled.jpeg","datePublished":"2023-07-04T14:31:18+00:00","dateModified":"2024-12-16T17:03:55+00:00","breadcrumb":{"@id":"https:\/\/travelsmartcampaign.org\/library\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelsmartcampaign.org\/library\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/travelsmartcampaign.org\/library\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\/#primaryimage","url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/AdobeStock_381933401-scaled.jpeg","contentUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/AdobeStock_381933401-scaled.jpeg","width":2560,"height":1621,"caption":"Side view of positive ethnic female in casual outfit with smartphone working on laptop and smiling while resting on comfortable armchair near window of train"},{"@type":"BreadcrumbList","@id":"https:\/\/travelsmartcampaign.org\/library\/umfrage-zeigt-mehrheit-der-mitarbeitenden-in-schweizer-unternehmen-will-weniger-fliegen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/travelsmartcampaign.org\/"},{"@type":"ListItem","position":2,"name":"Umfrage zeigt: Mehrheit der Mitarbeitenden in Schweizer Unternehmen will weniger fliegen"}]},{"@type":"WebSite","@id":"https:\/\/travelsmartcampaign.org\/#website","url":"https:\/\/travelsmartcampaign.org\/","name":"Travel Smart","description":"","publisher":{"@id":"https:\/\/travelsmartcampaign.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelsmartcampaign.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/travelsmartcampaign.org\/#organization","name":"Travel Smart","url":"https:\/\/travelsmartcampaign.org\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/travelsmartcampaign.org\/#\/schema\/logo\/image\/","url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/travel-smart-min.jpeg","contentUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/travel-smart-min.jpeg","width":1200,"height":690,"caption":"Travel Smart"},"image":{"@id":"https:\/\/travelsmartcampaign.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/library\/8999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/library"}],"about":[{"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/types\/library"}],"version-history":[{"count":0,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/library\/8999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/media\/8943"}],"wp:attachment":[{"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/media?parent=8999"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/topic?post=8999"},{"taxonomy":"visibility","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/visibility?post=8999"},{"taxonomy":"post-country","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/post-country?post=8999"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/language?post=8999"},{"taxonomy":"category-post-type","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/category-post-type?post=8999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}