{"id":9001,"date":"2023-07-04T15:37:57","date_gmt":"2023-07-04T14:37:57","guid":{"rendered":"http:\/\/travelsmartcampaign.org\/?post_type=library&#038;p=9001"},"modified":"2024-12-16T18:06:31","modified_gmt":"2024-12-16T17:06:31","slug":"belgische-zakenreizer-wunschen-sich-eine-langlebige-reiszutat","status":"publish","type":"library","link":"https:\/\/travelsmartcampaign.org\/de\/library\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\/","title":{"rendered":"Belgische Zakenreizigers erhalten eine dauerhafte Reiszulassung"},"content":{"rendered":"<p><b>Mehr als drei der belgischen Sicherheitskr\u00e4fte sind nun auch vor der Pandemie gefeit. Die Mehrleistung der Arbeitnehmer wird auf eine wichtige Weise verringert, indem die Klimaauswirkungen des Unternehmens verringert werden und eine nachhaltige Reiseversicherung eingef\u00fchrt wird. Das wird aus einer neuen Umfrage hervorgehen \u2013 ein angemessenes Zeichen f\u00fcr uns \u201c<\/b><a href=\"https:\/\/www.bondbeterleefmilieu.be\/BusinessTravelPioneers\"><b>Pioniere der Gesch\u00e4ftsreisebranche<\/b><\/a><b>\u201d-Koalition!\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Der Tourist wird aufgrund der Pandemie viel schneller wieder zum Flughafen und zum Touristenziel zur\u00fcckkehren. Auch f\u00fcr die kommenden Jahre ist es <\/span><a href=\"https:\/\/www2.deloitte.com\/us\/en\/insights\/focus\/transportation\/corporate-travel-study-2023.html\"><span style=\"font-weight: 400;\">Minderj\u00e4hriger <\/span><\/a><span style=\"font-weight: 400;\">Es wurde f\u00fcr 2019 ins Leben gerufen. Vier von zehn europ\u00e4ischen Unternehmen haben sich zum Ziel gesetzt, die Kundenzufriedenheit mit mehr als 20% zu steigern, um ihre Nachhaltigkeitsziele von 2030 zu erreichen. Aber was findet der belgische Zakenreiziger hier? Ipsos erh\u00e4lt 500 belgische Arbeitnehmer im Auftrag der <\/span><a href=\"http:\/\/travelsmartcampaign.org\/de\/\"><span style=\"font-weight: 400;\">Travel Smart-Kampagne<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Eine langlebige Reism\u00fchle<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">69% des zust\u00e4ndigen belgischen Herstellers hat festgestellt, dass das Unternehmen beim Spielen einer wichtigen Rolle gegen eine Klimaver\u00e4nderung vorgehen muss. Einerseits stellt sich heraus, dass ein Unternehmen, dessen Ziele erreicht werden m\u00fcssen, und andererseits, dass eine Reisegenehmigung erforderlich ist. 71% weist darauf hin, dass ein wichtiger Faktor bei der Verringerung der Klimaauswirkungen eines Unternehmens eine Rolle spielen wird.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Eine dauerhafte Reiszubereitung wird durchgef\u00fchrt, wenn nicht anders angegeben. f\u00fcr 1-op-1-Meetings, und f\u00fcr willkommene Zugfahrten, wie zum Beispiel <\/span><a href=\"https:\/\/www.kuleuven.be\/duurzaamheid\/duurzaam-reisbeleid\/witte-en-grijze-lijst\"><span style=\"font-weight: 400;\">KU Leuven<\/span><\/a><span style=\"font-weight: 400;\"> tut es. Die Auswirkungen von Flugunf\u00e4llen, die noch nicht aufgetreten sind, k\u00f6nnen durch <\/span><i><span style=\"font-weight: 400;\">Wirtschaftsklasse <\/span><\/i><span style=\"font-weight: 400;\">die Vliegen oder T\u00fctenlandungen zu beseitigen. <\/span><a href=\"https:\/\/drive.google.com\/file\/d\/1nHYjcikUag6YRIi6xyITp0HyVPGanYNK\/view\"><span style=\"font-weight: 400;\">Hier<\/span><\/a><span style=\"font-weight: 400;\"> eine vollst\u00e4ndige \u00dcbersicht \u00fcber bew\u00e4hrte Vorgehensweisen f\u00fcr eine nachhaltige Reiseplanung.\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Kein Greenwashing<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Die belgischen Arbeitnehmer verzeichnen selbst die Anzahl der Online-Meetings (43%), die Verwendung anderer Transportmittel (38%) und die Verringerung h\u00e4ufiger Fahrten (32%), um die Auswirkungen \u00e4hnlicher Fahrten zu begrenzen. Weniger als 10 % der Arbeitnehmer beim Kauf von <\/span><i><span style=\"font-weight: 400;\">Nachhaltige Flugkraftstoffe <\/span><\/i><span style=\"font-weight: 400;\">(16%) des Emissionsausgleichs (12%). Aber gut, wollen testaankoop dienende samen mit een 20-tal andere organisationisaties een <\/span><a href=\"https:\/\/www.vrt.be\/vrtnws\/nl\/2023\/06\/21\/europese-klacht-tegen-greenwashing-door-luchtvaartmaatschappijen\/\"><span style=\"font-weight: 400;\">klatsch <\/span><\/a><span style=\"font-weight: 400;\">Gegen\u00fcber europ\u00e4ischen Luftfahrtgesellschaften ist es praktisch, diese L\u00e4nder dauerhaft zu nutzen.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Die richtigen Worte auf der Spur<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Als Unternehmen weniger unterwegs? Die folgenden Faktoren werden von den zust\u00e4ndigen Mitarbeitern am h\u00e4ufigsten f\u00fcr diese Bewertung herangezogen: bessere internationale Spurverbindungen (71%), ein h\u00f6herer Preis f\u00fcr nachhaltige Reisel\u00f6sungen (67%) und Investitionen in virtuelle Kommunikationstechnologie (66%).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die langlebigste Option ist die billigste, die man bekommen kann, das ist logisch. Hierf\u00fcr ist es an der ersten Stelle notwendig, dass ein regelm\u00e4\u00dfiger Preis f\u00fcr die Luftlinie gezahlt wird, unter anderem \u00fcber einen <\/span><a href=\"https:\/\/www.bondbeterleefmilieu.be\/artikel\/de-meest-sociale-taks-een-taks-op-veelvliegers\"><span style=\"font-weight: 400;\">Vielflieger-Taks<\/span><\/a><span style=\"font-weight: 400;\">. Anschlie\u00dfend k\u00f6nnen Sie ein St\u00fcck des Gutscheins mitnehmen: \u00fcber eine Nebenkostenabrechnung und eine Ausgabe der Reiseversicherung, <\/span><a href=\"https:\/\/www.transportenvironment.org\/discover\/new-study-solo-travelers-could-save-up-to-20-on-the-cost-of-night-train-tickets-in-europe\/\"><span style=\"font-weight: 400;\">Ticketpreis 20% vorbestellt<\/span><\/a><span style=\"font-weight: 400;\">. Mit der finanziellen Unterst\u00fctzung des Nachtzugs gab Minister Gilkinet insgesamt ein gutes Beispiel. Und hoffentlich auch <\/span><a href=\"https:\/\/www.consilium.europa.eu\/media\/60527\/st15380-xx22.pdf\"><span style=\"font-weight: 400;\">Abonnieren<\/span><\/a><span style=\"font-weight: 400;\"> von unserem Land aus, in Frankreich, Luxemburg, den Niederlanden und Portugal, um das Potenzial ehrgeiziger Regelungen f\u00fcr nahezu alle Gebiete auf europ\u00e4ischem Niveau zu erkunden, zu pr\u00fcfen.\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">Die Umfrage fand im April 23 durch Ipsos statt und wurde im Rahmen der Kampagne Travel Smart unter 1.500 Mitarbeitern in Belgien (500), der Schweiz (500) und Polen (500) durchgef\u00fchrt. Einzelne Arbeitnehmer arbeiten f\u00fcr eine Organisation mit mindestens 50 Arbeitnehmern zusammen, unter anderem in der Absicht, eine Marke zu gr\u00fcnden.<\/span><\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-9002\" src=\"http:\/\/travelsmartcampaign.org\/wp-content\/uploads\/visual-3-NL-1024x576.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/visual-3-NL-1024x576.png 1024w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/visual-3-NL-300x169.png 300w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/visual-3-NL-768x432.png 768w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/visual-3-NL-1536x864.png 1536w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/visual-3-NL-18x10.png 18w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/visual-3-NL.png 1920w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Meer dan drie op vijf Belgische zakenreizigers vliegt nu minder dan voor de pandemie. De meerderheid van de werknemers vindt minder vliegen bovendien een belangrijke manier om de klimaatimpact van het bedrijf te verminderen en wenst dat er een duurzaam reisbeleid wordt ingevoerd. Dat blijkt uit een nieuwe enqu\u00eate &#8211; een bemoedigend signaal voor onze [&hellip;]<\/p>\n","protected":false},"featured_media":8848,"template":"","topic":[],"visibility":[55],"post-country":[30],"language":[37],"category-post-type":[232],"class_list":["post-9001","library","type-library","status-publish","has-post-thumbnail","hentry","visibility-open","post-country-belgium","language-dutch","category-post-type-survey"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Belgische zakenreizigers willen een duurzaam reisbeleid - Travel Smart Campaign<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelsmartcampaign.org\/de\/bibliothek\/belgische-zakenreizer-wunschen-sich-eine-langlebige-reiszutat\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Belgische zakenreizigers willen een duurzaam reisbeleid - Travel Smart Campaign\" \/>\n<meta property=\"og:description\" content=\"Meer dan drie op vijf Belgische zakenreizigers vliegt nu minder dan voor de pandemie. De meerderheid van de werknemers vindt minder vliegen bovendien een belangrijke manier om de klimaatimpact van het bedrijf te verminderen en wenst dat er een duurzaam reisbeleid wordt ingevoerd. Dat blijkt uit een nieuwe enqu\u00eate &#8211; een bemoedigend signaal voor onze [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelsmartcampaign.org\/de\/bibliothek\/belgische-zakenreizer-wunschen-sich-eine-langlebige-reiszutat\/\" \/>\n<meta property=\"og:site_name\" content=\"Travel Smart Campaign\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-16T17:06:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/pexels-fauxels-3183165-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2217\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\\\/\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\\\/\",\"name\":\"Belgische zakenreizigers willen een duurzaam reisbeleid - Travel Smart Campaign\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/pexels-fauxels-3183165-scaled.jpg\",\"datePublished\":\"2023-07-04T14:37:57+00:00\",\"dateModified\":\"2024-12-16T17:06:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/pexels-fauxels-3183165-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/pexels-fauxels-3183165-scaled.jpg\",\"width\":2217,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Belgische zakenreizigers willen een duurzaam reisbeleid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#website\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\",\"name\":\"Travel Smart\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/travelsmartcampaign.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#organization\",\"name\":\"Travel Smart\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/travel-smart-min.jpeg\",\"contentUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/travel-smart-min.jpeg\",\"width\":1200,\"height\":690,\"caption\":\"Travel Smart\"},\"image\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Belgische Gesch\u00e4ftsreisende wollen eine nachhaltige Reisepolitik \u2013 Kampagne Travel Smart","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelsmartcampaign.org\/de\/bibliothek\/belgische-zakenreizer-wunschen-sich-eine-langlebige-reiszutat\/","og_locale":"de_DE","og_type":"article","og_title":"Belgische zakenreizigers willen een duurzaam reisbeleid - Travel Smart Campaign","og_description":"Meer dan drie op vijf Belgische zakenreizigers vliegt nu minder dan voor de pandemie. De meerderheid van de werknemers vindt minder vliegen bovendien een belangrijke manier om de klimaatimpact van het bedrijf te verminderen en wenst dat er een duurzaam reisbeleid wordt ingevoerd. Dat blijkt uit een nieuwe enqu\u00eate &#8211; een bemoedigend signaal voor onze [&hellip;]","og_url":"https:\/\/travelsmartcampaign.org\/de\/bibliothek\/belgische-zakenreizer-wunschen-sich-eine-langlebige-reiszutat\/","og_site_name":"Travel Smart Campaign","article_modified_time":"2024-12-16T17:06:31+00:00","og_image":[{"width":2217,"height":2560,"url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/pexels-fauxels-3183165-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelsmartcampaign.org\/library\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\/","url":"https:\/\/travelsmartcampaign.org\/library\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\/","name":"Belgische Gesch\u00e4ftsreisende wollen eine nachhaltige Reisepolitik \u2013 Kampagne Travel Smart","isPartOf":{"@id":"https:\/\/travelsmartcampaign.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelsmartcampaign.org\/library\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\/#primaryimage"},"image":{"@id":"https:\/\/travelsmartcampaign.org\/library\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\/#primaryimage"},"thumbnailUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/pexels-fauxels-3183165-scaled.jpg","datePublished":"2023-07-04T14:37:57+00:00","dateModified":"2024-12-16T17:06:31+00:00","breadcrumb":{"@id":"https:\/\/travelsmartcampaign.org\/library\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelsmartcampaign.org\/library\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/travelsmartcampaign.org\/library\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\/#primaryimage","url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/pexels-fauxels-3183165-scaled.jpg","contentUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/pexels-fauxels-3183165-scaled.jpg","width":2217,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/travelsmartcampaign.org\/library\/belgische-zakenreizigers-willen-een-duurzaam-reisbeleid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/travelsmartcampaign.org\/"},{"@type":"ListItem","position":2,"name":"Belgische zakenreizigers willen een duurzaam reisbeleid"}]},{"@type":"WebSite","@id":"https:\/\/travelsmartcampaign.org\/#website","url":"https:\/\/travelsmartcampaign.org\/","name":"Travel Smart","description":"","publisher":{"@id":"https:\/\/travelsmartcampaign.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelsmartcampaign.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/travelsmartcampaign.org\/#organization","name":"Travel Smart","url":"https:\/\/travelsmartcampaign.org\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/travelsmartcampaign.org\/#\/schema\/logo\/image\/","url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/travel-smart-min.jpeg","contentUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/travel-smart-min.jpeg","width":1200,"height":690,"caption":"Travel Smart"},"image":{"@id":"https:\/\/travelsmartcampaign.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/library\/9001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/library"}],"about":[{"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/types\/library"}],"version-history":[{"count":0,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/library\/9001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/media\/8848"}],"wp:attachment":[{"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/media?parent=9001"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/topic?post=9001"},{"taxonomy":"visibility","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/visibility?post=9001"},{"taxonomy":"post-country","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/post-country?post=9001"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/language?post=9001"},{"taxonomy":"category-post-type","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/de\/wp-json\/wp\/v2\/category-post-type?post=9001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}