{"id":20329,"date":"2026-05-13T13:06:27","date_gmt":"2026-05-13T12:06:27","guid":{"rendered":"https:\/\/travelsmartcampaign.org\/?post_type=library&#038;p=20329"},"modified":"2026-05-13T13:47:54","modified_gmt":"2026-05-13T12:47:54","slug":"festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers","status":"publish","type":"library","link":"https:\/\/travelsmartcampaign.org\/es\/library\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\/","title":{"rendered":"Festival de Cannes: \u00bfhay medidas reales para limitar el uso de carbono en los trajes de los festivaleros?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Hier , le Festival de Cannes a accueilli\u00a0 des dizaines de milliers de personnes venues du monde entier. Mais avant de pouvoir monter les marches et fouler le tapis rouge, beaucoup prendront l\u2019avion, voire m\u00eame un jet priv\u00e9, avec \u00e0 la cl\u00e9, une lourde empreinte carbone.\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.nature.com\/articles\/s43247-024-01775-z\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Selon une \u00e9tude parue en 2024<\/span><\/a><span style=\"font-weight: 400;\">, Cannes est l&#8217;un des \u00e9v\u00e9nements mondiaux les plus \u00e9metteurs en gaz \u00e0 effet de serre, avec 640 atterrissages ou d\u00e9collages de jets priv\u00e9s attribu\u00e9s \u00e0 l\u2019\u00e9dition 2023. <\/span><a href=\"https:\/\/drive.usercontent.google.com\/download?id=1gWv1oQCC9jmnJ-Xi13FCr-rSnVJUGno7&amp;authuser=0&amp;acrobatPromotionSource=gdrive_chrome-list\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">L\u2019ann\u00e9e derni\u00e8re<\/span><\/a><span style=\"font-weight: 400;\">, 620 vols en jet priv\u00e9 ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9s par l\u2019\u00e9v\u00e9nement. Ce chiffre \u00e9quivaut \u00e0 une voiture thermique qui ferait environ 700 fois le tour de la Terre.[1]<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le Festival s\u2019est pourtant engag\u00e9 \u00e0 r\u00e9duire de 21 % son empreinte carbone d\u2019ici 2030 par rapport \u00e0 2019. Il s\u2019agit d\u2019un objectif relativement peu ambitieux au regard de l\u2019engagement europ\u00e9en de r\u00e9duire les \u00e9missions de 55%. Malgr\u00e9 cela, le nombre de jets priv\u00e9s n\u2019a quasiment pas diminu\u00e9 entre 2023 et 2025.<br \/>\n<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cette question des voyages reste largement ignor\u00e9e par les organisateurs. Elle est pourtant centrale : selon le site officiel du Festival, les d\u00e9placements des visiteurs accr\u00e9dit\u00e9s pour se rendre \u00e0 Cannes ont repr\u00e9sent\u00e9 93% du bilan carbone de l\u2019\u00e9v\u00e9nement en 2025 [2]. Malgr\u00e9 cela, la <\/span><a href=\"https:\/\/cdn.festival-cannes.com\/media\/uploads\/2024\/04\/comm-charte-v2-12fev24-1.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">charte environnementale<\/span><\/a><span style=\"font-weight: 400;\"> de 2024 ne contient aucune action concr\u00e8te pour agir sur les moyens de transport utilis\u00e9s par les acteurs, r\u00e9alisateurs et autres invit\u00e9s pour venir sur la Croisette. L\u2019organisation a beaucoup communiqu\u00e9 sur la fr\u00e9quence de changement du tapis rouge et des moquettes, ou encore sur la flotte de voitures \u00e9lectriques, mais tous ces \u00e9l\u00e9ments p\u00e8sent peu face \u00e0 l\u2019impact \u00e9norme des d\u00e9placements en avion vers Cannes.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ce manque d\u2019action n\u2019est pas sans cons\u00e9quences. Le bilan carbone du Festival de Cannes s\u2019est \u00e9lev\u00e9 \u00e0 49 900 tonnes de CO\u2082e en 2025, en hausse de 2% par rapport \u00e0 2019. Cette trajectoire, aliment\u00e9e par la hausse des \u00e9missions li\u00e9s aux trajets des festivaliers vers Cannes (+6%), est en totale contradiction avec les engagements pris par le Festival.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L\u2019empreinte carbone du festival de Cannes n\u2019est pas un \u00e9piph\u00e9nom\u00e8ne. Il soul\u00e8ve la question douloureuse du partage de l\u2019effort dans la lutte contre le changement climatique. Le festival de Cannes serait-il au-dessus des objectifs europ\u00e9ens et fran\u00e7ais qui s\u2019appliquent aux autres secteurs ?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il est donc plus que temps pour les organisateurs de r\u00e9agir. Nous demandons donc <\/span><b>l\u2019adoption d\u2019une politique voyage beaucoup plus ambitieuse<\/b><span style=\"font-weight: 400;\"> de la part du Festival. Les participants arrivant d\u2019un autre continent devraient ainsi \u00eatre incit\u00e9s \u00e0 prendre <\/span><b>un vol commercial plut\u00f4t qu\u2019un jet priv\u00e9<\/b><span style=\"font-weight: 400;\">. Ce dernier \u00e9met en effet au moins quatre fois plus de CO\u2082 par passager qu\u2019un avion classique.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pour toutes les personnes venant d\u2019Europe, la politique voyage devrait pr\u00e9coniser <\/span><b>l\u2019utilisation du train ou de la voiture \u00e9lectrique<\/b><span style=\"font-weight: 400;\"> au lieu de l\u2019avion. Le Festival de Cannes pourrait par exemple s\u2019inspirer du label Ecoprod [3], soutenu notamment par TF1 et France T\u00e9l\u00e9visions, qui permet de certifier des productions cin\u00e9matographiques \u00e9co-responsables \u00e0 partir de crit\u00e8res pr\u00e9cis, comme prendre le train plut\u00f4t que l\u2019avion pour les longs d\u00e9placements lorsqu\u2019ils sont inf\u00e9rieurs \u00e0 cinq heures.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Alors que le d\u00e9r\u00e8glement climatique s\u2019aggrave, le Festival de Cannes, ne peut plus fermer les yeux sur son impact et se contenter de mesures cosm\u00e9tiques. Il doit prendre conscience de son pouvoir d\u2019influence et l\u2019utiliser pour questionner les pratiques de voyages les plus \u00e9mettrices.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><b>Note <\/b><span style=\"font-weight: 400;\">[1] Ce chiffre ne tient pas compte de l&#8217;a\u00e9roport de Cannes, conform\u00e9ment \u00e0 l&#8217;\u00e9tude universitaire. Si l&#8217;on y ajoutait l&#8217;a\u00e9roport de Cannes, le total s&#8217;\u00e9l\u00e8verait \u00e0 764 jets priv\u00e9s, ce qui \u00e9quivaut \u00e0 une voiture thermique qui ferait environ 779 fois le tour de la Terre.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">[2] Tous les chiffres sur les engagements et le bilan carbone du Festival sont issus du site officiel du Festival de Cannes : <\/span><a href=\"https:\/\/www.festival-cannes.com\/qui-sommes-nous\/le-festival-s-engage\/pour-l-environnement\/#:~:text=Depuis%202021%2C%20le%20Festival%20s,jusqu'au%20transport%20des%20festivaliers\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">https:\/\/www.festival-cannes.com\/qui-sommes-nous\/le-festival-s-engage\/pour-l-environnement\/#:~:text=Depuis%202021%2C%20le%20Festival%20s,jusqu&#8217;au%20transport%20des%20festivaliers<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">[3] Lien vers le r\u00e9f\u00e9renciel du Label d\u2019 Ecoprod:\u00a0 <a href=\"https:\/\/ecoprod.com\/wp-content\/uploads\/2025\/12\/ReferentielLabelEcoprod17Novembre2025.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/ecoprod.com\/wp-content\/uploads\/2025\/12\/ReferentielLabelEcoprod17Novembre2025.pdf<\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Signataires\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Denise Auclair, responsable de la campagne Travel Smart \u00e0<a href=\"https:\/\/www.transportenvironment.org\/?gad_source=1&amp;gad_campaignid=1746291099&amp;gbraid=0AAAAADdSzN-Jty3OV0mzeIYnv4_OscJRR&amp;gclid=CjwKCAjwwpDQBhAuEiwAa-4Wo3Byl-nTgNtAQ2hVN5NeRi2fY0NeTc2C04cFN1LjyJw92EyVL_nElBoCgD0QAvD_BwE\" target=\"_blank\" rel=\"noopener\"> T&amp;E<\/a>\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Airy Chr\u00e9tien, cofondateur du <a href=\"https:\/\/collectifcitoyen06.org\/\" target=\"_blank\" rel=\"noopener\">Collectif Citoyen 06<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En total contradicci\u00f3n con sus propios compromisos, el empreinte carbone du Festival de Cannes continue d'augmenter.<\/p>","protected":false},"featured_media":20326,"template":"","topic":[199,96,264,203,263,237,165],"visibility":[],"post-country":[31],"language":[38],"category-post-type":[43],"class_list":["post-20329","library","type-library","status-publish","has-post-thumbnail","hentry","topic-air-travel","topic-business-travel","topic-cannes-film-festival","topic-emissions-reduction","topic-oil-crisis","topic-private-jets","topic-rail","post-country-france","language-french","category-post-type-opinion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festival de Cannes : \u00e0 quand des vraies mesures pour limiter l\u2019empreinte carbone des trajets des festivaliers ? - Travel Smart Campaign<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelsmartcampaign.org\/es\/biblioteca\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festival de Cannes : \u00e0 quand des vraies mesures pour limiter l\u2019empreinte carbone des trajets des festivaliers ? - Travel Smart Campaign\" \/>\n<meta property=\"og:description\" content=\"En totale contradiction avec ses propres engagements, l\u2019empreinte carbone du Festival de Cannes continue d\u2019augmenter.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelsmartcampaign.org\/es\/biblioteca\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\/\" \/>\n<meta property=\"og:site_name\" content=\"Travel Smart Campaign\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T12:47:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/pexels-myatezhny39-2422404-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1697\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\\\/\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\\\/\",\"name\":\"Festival de Cannes : \u00e0 quand des vraies mesures pour limiter l\u2019empreinte carbone des trajets des festivaliers ? - Travel Smart Campaign\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/pexels-myatezhny39-2422404-scaled.jpg\",\"datePublished\":\"2026-05-13T12:06:27+00:00\",\"dateModified\":\"2026-05-13T12:47:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/pexels-myatezhny39-2422404-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/pexels-myatezhny39-2422404-scaled.jpg\",\"width\":2560,\"height\":1697},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival de Cannes : \u00e0 quand des vraies mesures pour limiter l\u2019empreinte carbone des trajets des festivaliers ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#website\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\",\"name\":\"Travel Smart\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/travelsmartcampaign.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#organization\",\"name\":\"Travel Smart\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/travel-smart-min.jpeg\",\"contentUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/travel-smart-min.jpeg\",\"width\":1200,\"height\":690,\"caption\":\"Travel Smart\"},\"image\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival de Cannes: \u00bfhay medidas reales para limitar la emisi\u00f3n de carbono de los residuos de los festivales? - Campa\u00f1a Travel Smart","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelsmartcampaign.org\/es\/biblioteca\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\/","og_locale":"es_ES","og_type":"article","og_title":"Festival de Cannes : \u00e0 quand des vraies mesures pour limiter l\u2019empreinte carbone des trajets des festivaliers ? - Travel Smart Campaign","og_description":"En totale contradiction avec ses propres engagements, l\u2019empreinte carbone du Festival de Cannes continue d\u2019augmenter.","og_url":"https:\/\/travelsmartcampaign.org\/es\/biblioteca\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\/","og_site_name":"Travel Smart Campaign","article_modified_time":"2026-05-13T12:47:54+00:00","og_image":[{"width":2560,"height":1697,"url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/pexels-myatezhny39-2422404-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelsmartcampaign.org\/library\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\/","url":"https:\/\/travelsmartcampaign.org\/library\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\/","name":"Festival de Cannes: \u00bfhay medidas reales para limitar la emisi\u00f3n de carbono de los residuos de los festivales? - Campa\u00f1a Travel Smart","isPartOf":{"@id":"https:\/\/travelsmartcampaign.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelsmartcampaign.org\/library\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\/#primaryimage"},"image":{"@id":"https:\/\/travelsmartcampaign.org\/library\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\/#primaryimage"},"thumbnailUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/pexels-myatezhny39-2422404-scaled.jpg","datePublished":"2026-05-13T12:06:27+00:00","dateModified":"2026-05-13T12:47:54+00:00","breadcrumb":{"@id":"https:\/\/travelsmartcampaign.org\/library\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelsmartcampaign.org\/library\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/travelsmartcampaign.org\/library\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\/#primaryimage","url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/pexels-myatezhny39-2422404-scaled.jpg","contentUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/pexels-myatezhny39-2422404-scaled.jpg","width":2560,"height":1697},{"@type":"BreadcrumbList","@id":"https:\/\/travelsmartcampaign.org\/library\/festival-de-cannes-a-quand-des-vraies-mesures-pour-limiter-lempreinte-carbone-des-trajets-des-festivaliers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/travelsmartcampaign.org\/"},{"@type":"ListItem","position":2,"name":"Festival de Cannes : \u00e0 quand des vraies mesures pour limiter l\u2019empreinte carbone des trajets des festivaliers ?"}]},{"@type":"WebSite","@id":"https:\/\/travelsmartcampaign.org\/#website","url":"https:\/\/travelsmartcampaign.org\/","name":"Travel Smart","description":"","publisher":{"@id":"https:\/\/travelsmartcampaign.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelsmartcampaign.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/travelsmartcampaign.org\/#organization","name":"Travel Smart","url":"https:\/\/travelsmartcampaign.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/travelsmartcampaign.org\/#\/schema\/logo\/image\/","url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/travel-smart-min.jpeg","contentUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/travel-smart-min.jpeg","width":1200,"height":690,"caption":"Travel Smart"},"image":{"@id":"https:\/\/travelsmartcampaign.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/library\/20329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/library"}],"about":[{"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/types\/library"}],"version-history":[{"count":3,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/library\/20329\/revisions"}],"predecessor-version":[{"id":20336,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/library\/20329\/revisions\/20336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/media\/20326"}],"wp:attachment":[{"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/media?parent=20329"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/topic?post=20329"},{"taxonomy":"visibility","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/visibility?post=20329"},{"taxonomy":"post-country","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/post-country?post=20329"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/language?post=20329"},{"taxonomy":"category-post-type","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/category-post-type?post=20329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}