{"id":4375,"date":"2023-03-15T00:01:45","date_gmt":"2023-03-14T23:01:45","guid":{"rendered":"http:\/\/travelsmartcampaign.org\/?post_type=library&#038;p=4375"},"modified":"2023-03-15T10:27:10","modified_gmt":"2023-03-15T09:27:10","slug":"el-85-de-las-empresas-globales-no-tienen-planes-creibles-para-reducir-las-emisiones-de-los-vuelos-corporativos","status":"publish","type":"library","link":"https:\/\/travelsmartcampaign.org\/es\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/","title":{"rendered":"85% de empresas globales no tienen planes cre\u00edbles para reducir las emisiones de los vuelos corporativos"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">85% de las empresas de todo el mundo no fijan objetivos ambiciosos para reducir las emisiones de los viajes corporativos, seg\u00fan revela la segunda edici\u00f3n de una clasificaci\u00f3n sobre viajes de negocios realizada por The Travel Smart Campaign.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">S\u00f3lo 50 empresas de 322 han fijado objetivos para reducir las emisiones de los viajes de negocios. De las empresas que tienen objetivos, s\u00f3lo cuatro cumplen la \"regla de oro\", es decir, informan de las emisiones de los viajes en avi\u00f3n y se comprometen a reducirlas en 50% o m\u00e1s, para 2025 o antes. Se trata de Novo Nordisk (Farmac\u00e9utica, Dinamarca), Swiss Re (Finanzas, Suiza), Fidelity International (Finanzas, Reino Unido) y <\/span><span style=\"font-weight: 400;\">ABN Amro (Finanzas, Pa\u00edses Bajos).<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-6454\" src=\"http:\/\/travelsmartcampaign.org\/wp-content\/uploads\/Original_Infographic-2-Ranking-card-for-companies-5-1024x576.png\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/Original_Infographic-2-Ranking-card-for-companies-5-1024x576.png 1024w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/Original_Infographic-2-Ranking-card-for-companies-5-300x169.png 300w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/Original_Infographic-2-Ranking-card-for-companies-5-768x432.png 768w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/Original_Infographic-2-Ranking-card-for-companies-5-1536x864.png 1536w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/Original_Infographic-2-Ranking-card-for-companies-5-18x10.png 18w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/Original_Infographic-2-Ranking-card-for-companies-5.png 1920w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">En el primer informe sobre emisiones de gases de efecto invernadero distintas del CO2 relacionadas con los vuelos de negocios, la clasificaci\u00f3n revela que 40 empresas est\u00e1n a la cabeza al informar sobre todas las emisiones de gases de efecto invernadero asociadas a los vuelos corporativos. Los gigantes farmac\u00e9uticos AstraZeneca y Pfizer y las empresas de consultor\u00eda Boston Consulting Group y Deloitte dan ejemplo al tener en cuenta en sus informes todo el impacto de los vuelos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El impacto clim\u00e1tico de los vuelos de negocios va m\u00e1s all\u00e1 de las emisiones de CO2. Adem\u00e1s de CO2, los motores de los aviones emiten otros gases (\u00f3xidos nitrosos, di\u00f3xido de azufre y agua) y part\u00edculas (holl\u00edn).  Se trata de emisiones distintas del CO2. <\/span><a href=\"https:\/\/www.easa.europa.eu\/en\/document-library\/research-reports\/report-commission-european-parliament-and-council\"><span style=\"font-weight: 400;\">calcula <\/span><\/a><span style=\"font-weight: 400;\">que representan dos tercios del calentamiento clim\u00e1tico total debido a los vuelos. Sin embargo, s\u00f3lo muy pocas empresas reflejan el impacto total de los vuelos de negocios teniendo en cuenta los efectos distintos del CO2.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Denise Auclair, gerente de viajes corporativos de Transport &amp; Environment, dijo:<\/span><i><span style=\"font-weight: 400;\"> \"Las empresas hacen la vista gorda ante los perjuicios de volar por motivos de trabajo. La mayor\u00eda de las empresas apenas toman medidas en relaci\u00f3n con los vuelos de negocios, lo que hace que cualquier otro objetivo en materia de viajes carezca de sentido en el contexto de la lucha contra el cambio clim\u00e1tico. S\u00f3lo unas pocas empresas punteras se alinean con la ciencia informando sobre las emisiones distintas del CO2, la parte oculta del iceberg del impacto clim\u00e1tico total de la aviaci\u00f3n\".<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Volkswagen, KPMG y Johnson &amp; Johnson son los tres principales emisores<\/span><span style=\"font-weight: 400;\"> de la clasificaci\u00f3n Travel Smart sin un objetivo de reducci\u00f3n de las emisiones de sus viajes (1). Pero fijar tales objetivos es posible y necesario, como han hecho empresas de tama\u00f1o y sector similares como McKinsey, Deloitte y AstraZeneca.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El estudio muestra que si 10% de empresas (los mayores emisores del ranking) establecieran objetivos de reducci\u00f3n de 50%, esto ser\u00eda la mitad del camino hacia el logro del objetivo global de -50% en emisiones de viajes a\u00e9reos corporativos para 2025. Reducir las emisiones de la aviaci\u00f3n es ahora m\u00e1s crucial que nunca, si queremos mantenernos dentro de un margen de 1,5\u00b0C de calentamiento global.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para la d\u00e9cada cr\u00edtica hasta 2030, la mejor manera de reducir las emisiones de la aviaci\u00f3n es volar menos, ya que el momento para aumentar el uso de combustibles sostenibles y aviones de cero emisiones es actualmente posterior a 2030, y la compensaci\u00f3n no puede sustituir la reducci\u00f3n de emisiones.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La campa\u00f1a Travel Smart insta a las empresas a fijarse objetivos ambiciosos para reducir las emisiones de los viajes corporativos, cambiar el avi\u00f3n por el tren siempre que sea posible y privilegiar las videoconferencias como sustituto de los vuelos de larga distancia.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Denise Auclair concluye: \u201c<\/span><i><span style=\"font-weight: 400;\">Los mayores emisores tienen un papel desproporcionado a la hora de reducir las emisiones de sus vuelos corporativos. Los medios para conseguirlo son m\u00e1s accesibles que nunca: viajes en tren cuando las distancias lo permiten y videoconferencias para evitar vuelos de larga distancia.\"<\/span><\/i><\/p>\n<p><b>Nota para los editores:\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Transport &amp; Environment, junto con una coalici\u00f3n de socios globales, lanz\u00f3 la campa\u00f1a Travel Smart en 2022 con una edici\u00f3n anual de una clasificaci\u00f3n corporativa sobre pr\u00e1cticas sostenibles en viajes de negocios. La campa\u00f1a interact\u00faa con las empresas, con el objetivo de que reduzcan sus emisiones de viajes corporativos en 50% o m\u00e1s de los niveles anteriores a Covid para 2025 o antes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El ranking Travel Smart clasifica a 322 empresas estadounidenses, europeas e indias seg\u00fan 10 indicadores, relacionados con las emisiones de los viajes a\u00e9reos, los objetivos de reducci\u00f3n y la presentaci\u00f3n de informes. Los principales viajeros globales de los 17 pa\u00edses del ranking representan una parte considerable de los viajes de negocios en todo el mundo. El an\u00e1lisis arroja luz sobre los importantes esfuerzos que algunas empresas globales a\u00fan deben realizar para reducir sus emisiones de viajes corporativos. Las empresas reciben una calificaci\u00f3n A, B, C o D. En la edici\u00f3n de este a\u00f1o del ranking, 11 empresas obtuvieron una calificaci\u00f3n A, 38 una B, mientras que la inmensa mayor\u00eda recibi\u00f3 una C (212) y 61 empresas obtuvieron una calificaci\u00f3n D junto a su nombre.\u00a0<\/span><\/p>\n<p>(1) <span style=\"font-weight: 400;\">Seg\u00fan el informe de emisiones de 2019<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Las mayores empresas del mundo no fijan objetivos para la forma de viaje de negocios que m\u00e1s afecta al clima: el avi\u00f3n.<\/p>","protected":false},"featured_media":3122,"template":"","topic":[],"visibility":[],"post-country":[26],"language":[27],"category-post-type":[28],"class_list":["post-4375","library","type-library","status-publish","has-post-thumbnail","hentry","post-country-global","language-english","category-post-type-press-release"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>85% of global companies don\u2019t have credible plans to reduce corporate flying emissions - Travel Smart Campaign<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelsmartcampaign.org\/es\/biblioteca\/el-85-de-las-empresas-globales-no-tienen-planes-creibles-para-reducir-las-emisiones-de-los-vuelos-corporativos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"85% of global companies don\u2019t have credible plans to reduce corporate flying emissions - Travel Smart Campaign\" \/>\n<meta property=\"og:description\" content=\"World\u2019s largest companies fail to set targets on most climate intensive form of business travel - air travel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelsmartcampaign.org\/es\/biblioteca\/el-85-de-las-empresas-globales-no-tienen-planes-creibles-para-reducir-las-emisiones-de-los-vuelos-corporativos\/\" \/>\n<meta property=\"og:site_name\" content=\"Travel Smart Campaign\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-15T09:27:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/airplane-image-travel-smart-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/\",\"name\":\"85% of global companies don\u2019t have credible plans to reduce corporate flying emissions - Travel Smart Campaign\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/airplane-image-travel-smart-1-scaled.jpg\",\"datePublished\":\"2023-03-14T23:01:45+00:00\",\"dateModified\":\"2023-03-15T09:27:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/airplane-image-travel-smart-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/airplane-image-travel-smart-1-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"airplane image\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"85% of global companies don\u2019t have credible plans to reduce corporate flying emissions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#website\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\",\"name\":\"Travel Smart\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/travelsmartcampaign.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#organization\",\"name\":\"Travel Smart\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/travel-smart-min.jpeg\",\"contentUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/travel-smart-min.jpeg\",\"width\":1200,\"height\":690,\"caption\":\"Travel Smart\"},\"image\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"85% de empresas globales no tienen planes cre\u00edbles para reducir las emisiones de los vuelos corporativos - Campa\u00f1a Travel Smart","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelsmartcampaign.org\/es\/biblioteca\/el-85-de-las-empresas-globales-no-tienen-planes-creibles-para-reducir-las-emisiones-de-los-vuelos-corporativos\/","og_locale":"es_ES","og_type":"article","og_title":"85% of global companies don\u2019t have credible plans to reduce corporate flying emissions - Travel Smart Campaign","og_description":"World\u2019s largest companies fail to set targets on most climate intensive form of business travel - air travel.","og_url":"https:\/\/travelsmartcampaign.org\/es\/biblioteca\/el-85-de-las-empresas-globales-no-tienen-planes-creibles-para-reducir-las-emisiones-de-los-vuelos-corporativos\/","og_site_name":"Travel Smart Campaign","article_modified_time":"2023-03-15T09:27:10+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/airplane-image-travel-smart-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/","url":"https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/","name":"85% de empresas globales no tienen planes cre\u00edbles para reducir las emisiones de los vuelos corporativos - Campa\u00f1a Travel Smart","isPartOf":{"@id":"https:\/\/travelsmartcampaign.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/#primaryimage"},"image":{"@id":"https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/#primaryimage"},"thumbnailUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/airplane-image-travel-smart-1-scaled.jpg","datePublished":"2023-03-14T23:01:45+00:00","dateModified":"2023-03-15T09:27:10+00:00","breadcrumb":{"@id":"https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/#primaryimage","url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/airplane-image-travel-smart-1-scaled.jpg","contentUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/airplane-image-travel-smart-1-scaled.jpg","width":2560,"height":1707,"caption":"airplane image"},{"@type":"BreadcrumbList","@id":"https:\/\/travelsmartcampaign.org\/library\/85-of-global-companies-dont-have-credible-plans-to-reduce-corporate-flying-emissions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/travelsmartcampaign.org\/"},{"@type":"ListItem","position":2,"name":"85% of global companies don\u2019t have credible plans to reduce corporate flying emissions"}]},{"@type":"WebSite","@id":"https:\/\/travelsmartcampaign.org\/#website","url":"https:\/\/travelsmartcampaign.org\/","name":"Travel Smart","description":"","publisher":{"@id":"https:\/\/travelsmartcampaign.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelsmartcampaign.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/travelsmartcampaign.org\/#organization","name":"Travel Smart","url":"https:\/\/travelsmartcampaign.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/travelsmartcampaign.org\/#\/schema\/logo\/image\/","url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/travel-smart-min.jpeg","contentUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/travel-smart-min.jpeg","width":1200,"height":690,"caption":"Travel Smart"},"image":{"@id":"https:\/\/travelsmartcampaign.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/library\/4375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/library"}],"about":[{"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/types\/library"}],"version-history":[{"count":0,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/library\/4375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/media\/3122"}],"wp:attachment":[{"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/media?parent=4375"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/topic?post=4375"},{"taxonomy":"visibility","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/visibility?post=4375"},{"taxonomy":"post-country","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/post-country?post=4375"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/language?post=4375"},{"taxonomy":"category-post-type","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/es\/wp-json\/wp\/v2\/category-post-type?post=4375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}