{"id":18994,"date":"2025-10-27T00:01:28","date_gmt":"2025-10-26T23:01:28","guid":{"rendered":"http:\/\/travelsmartcampaign.org\/?post_type=library&#038;p=18994"},"modified":"2025-11-05T14:06:10","modified_gmt":"2025-11-05T13:06:10","slug":"geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken","status":"publish","type":"library","link":"https:\/\/travelsmartcampaign.org\/fr\/library\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\/","title":{"rendered":"D\u00e9penses d'exploitation : Les \u00e9missions de neuf grandes entreprises allemandes ont \u00e9t\u00e9 r\u00e9duites de 40 % par rapport \u00e0 2019"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Eine neue von T&amp;Es Travel Smart Kampagne durchgef\u00fchrte Analyse der Emissionen von Gesch\u00e4ftsreisen von neun deutschen Gro\u00dfunternehmen [1] zeigt, dass diese ihre Emissionen bei Reisen durchschnittlich um 40 Prozent\u00a0 im Vergleich zu 2019 reduziert haben.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Insgesamt best\u00e4tigt sich der positive Trend zur Reduzierung der Emissionen aus Gesch\u00e4ftsreisen. Dennoch zeigt die Analyse Unterschiede zwischen Unternehmen: Einige reduzieren ihre Emissionen um mehr als die H\u00e4lfte, w\u00e4hrend einige wenige ebenfalls einen Abw\u00e4rtstrend verzeichnen, der jedoch langsamer verl\u00e4uft. Die Nachz\u00fcgler m\u00fcssen mehr tun, um mit der neuen Normalit\u00e4t des Verzichts auf Gesch\u00e4ftsreisen Schritt zu halten. In Deutschland sind diese seit der Pandemie stark zur\u00fcckgegangen, laut dem <\/span><a href=\"https:\/\/www.youtube.com\/watch?v=UK9in-lxlTA\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Deutschen Reiseverband<\/span><\/a><span style=\"font-weight: 400;\"> um 44 Prozent im Jahr 2024 im Vergleich zu 2019.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">T&amp;Es <\/span><a href=\"http:\/\/travelsmartcampaign.org\/library\/corporate-travel-reduced-by-a-third-on-2019-levels-despite-increased-flying-by-merck-bosch-and-jpmorgan-chase\/\"><span style=\"font-weight: 400;\">globale Analyse<\/span><\/a><span style=\"font-weight: 400;\"> im Rahmen des Travel Smart Rankings 2025 zeigt, dass Unternehmen mit konkreten Zielen f\u00fcr Gesch\u00e4ftsreisen effektiver bei der Reduzierung ihrer Emissionen sind. Von den neun Unternehmen [2], die in der Analyse betrachtet wurden, hat nur Allianz konkrete Ziele f\u00fcr die Reduzierung der Emissionen aus Gesch\u00e4ftsreisen festgelegt. Die verbleibenden acht haben entweder gar keine entsprechenden Ziele oder nur ein umfassenderes Reduktionsziel, das viele Aktivit\u00e4ten des Unternehmens umfasst.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tats\u00e4chlich hat der Versicherungskonzern Allianz ein klares Ziel zur Reduzierung der Emissionen aus Gesch\u00e4ftsreisen bis 2030 festgelegt und mit 60 Prozent die h\u00f6chste Reduktion zwischen 2019 und 2024 erreicht. Dabei wurden <\/span><a href=\"https:\/\/www.allianz.com\/content\/dam\/onemarketing\/azcom\/Allianz_com\/sustainabilityreport\/2024\/Allianz-SE-Sustainability-Report-2024-short-version.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Ma\u00dfnahmen<\/span><\/a><span style=\"font-weight: 400;\"> wie die F\u00f6rderung der digitalen Zusammenarbeit und andere kohlenstoffarme Alternativen umgesetzt.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Bereiche wie die <\/span><a href=\"http:\/\/travelsmartcampaign.org\/library\/business-travel-emissions-by-major-global-consulting-firms-down-by-46-compared-with-2019\/\"><span style=\"font-weight: 400;\">Beratung<\/span><\/a><span style=\"font-weight: 400;\">, in denen Reisen einen erheblichen Anteil der Unternehmensemissionen ausmachen, sind f\u00fchrend bei der Emissionsreduzierung. Diese Branchendynamik erstreckt sich auf ein globales Unternehmen: SAP. Auch wenn SAP keine konkreten Ziele f\u00fcr Gesch\u00e4ftsreisen verfolgt, profitiert das Unternehmen von getroffenen Ma\u00dfnahmen wie Investitionen in virtuelle Technologien f\u00fcr Zusammenarbeit und Kommunikation sowie die Erhebung einer CO2-Abgabe auf Gesch\u00e4ftsfl\u00fcge, um Mitarbeitende dazu anzuregen, weniger zu fliegen oder stattdessen nachhaltigere Alternativen zu nutzen, wie aus SAPs aktuellsten Antwort auf den CDP-Fragebogen hervorgeht.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Im Gegensatz dazu hat der Chemieriese BASF, der sich kein Ziel f\u00fcr Gesch\u00e4ftsreisen gesetzt hat, seine Reiseemissionen bis 2024 nur um 12 Prozent unter das Niveau von 2019 gesenkt. \u00c4hnlich ist es bei Adidas. Das Unternehmen hat ein allgemeines<\/span><span style=\"font-weight: 400;\"> Reduktionsziel und verzeichnet lediglich minus 10 Prozent.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-19026\" src=\"http:\/\/travelsmartcampaign.org\/wp-content\/uploads\/DE.png\" alt=\"\" width=\"768\" height=\"1100\" srcset=\"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/DE.png 768w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/DE-209x300.png 209w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/DE-715x1024.png 715w, https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/DE-8x12.png 8w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Dieser R\u00fcckgang ist wahrscheinlich auf eine ver\u00e4nderte Einstellung deutscher Unternehmen zu Gesch\u00e4ftsreisen zur\u00fcckzuf\u00fchren. Virtuelle Tools f\u00fcr die Zusammenarbeit gelten als bequeme und effektive M\u00f6glichkeit, Meetings abzuhalten. Wenn physische Reisen notwendig sind, entscheiden sich Unternehmen zunehmend f\u00fcr nachhaltigere Alternativen wie die <\/span><a href=\"https:\/\/www.youtube.com\/watch?v=UK9in-lxlTA\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Bahn<\/span><\/a><span style=\"font-weight: 400;\">. 82 Prozent der deutschen Gesch\u00e4ftsreisenden w\u00e4hlen die Bahn f\u00fcr T\u00fcr-zu-T\u00fcr-Reisen von bis zu drei Stunden Dauer \u2013 und w\u00fcrden dies wahrscheinlich noch h\u00e4ufiger tun, wenn die <\/span><a href=\"http:\/\/travelsmartcampaign.org\/library\/business-travellers-and-environmental-organisations-across-europe-call-upon-german-government-and-political-decision-makers-to-ramp-up-rail\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">deutschen Bahnverbindungen<\/span><\/a><span style=\"font-weight: 400;\"> zuverl\u00e4ssiger w\u00fcrden.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die Reduzierung der <\/span><a href=\"https:\/\/table.media\/en\/climate\/feature\/domestic-flights-decline-reduces-greenhouse-gas-emissions\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Reisekosten<\/span><\/a><span style=\"font-weight: 400;\"> und das wachsende Umweltbewusstsein von Reisemanager:innen und Mitarbeitenden sind ebenfalls wichtige Faktoren. Tats\u00e4chlich gaben 63,5 Prozent der europ\u00e4ischen Befragten im aktuellen <\/span><a href=\"https:\/\/www.businesstravelnews.com\/Sustainable-Business-Travel\/2025\/The-Current-State-of-Play\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">BTN 2025 Sustainability Report<\/span><\/a><span style=\"font-weight: 400;\"> an, dass Klimabelange einen wesentlichen Einfluss auf ihre Reiseentscheidungen haben. Schlie\u00dflich sind viele Unternehmen auch durch die Notwendigkeit motiviert, Vorschriften wie die EU-Richtlinie zur Nachhaltigkeitsberichterstattung von Unternehmen (CSRD) einzuhalten. 52 Prozent der Unternehmen in dem genannten <\/span><a href=\"https:\/\/www.businesstravelnews.com\/Sustainable-Business-Travel\/2025\/The-Current-State-of-Play\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Bericht<\/span><\/a><span style=\"font-weight: 400;\"> nannten dies als Grund f\u00fcr die Reduzierung der Emissionen durch Gesch\u00e4ftsreisen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">T&amp;E und die Travel Smart Kampagne fordern deutsche Unternehmen auf, konkrete Ziele festzulegen, um die Emissionen aus Gesch\u00e4ftsreisen zwischen 2025 und 2030 um mindestens 50 Prozent gegen\u00fcber dem Niveau von 2019 zu senken.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dieses vorgeschlagene Ziel wurde auf der Grundlage von T&amp;Es <\/span><a href=\"https:\/\/www.transportenvironment.org\/articles\/2050roadmap\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Roadmap<\/span><\/a><span style=\"font-weight: 400;\"> festgelegt, die zeigt, dass die Emissionen aus Gesch\u00e4ftsreisen bis 2030 um 50 Prozent reduziert werden m\u00fcssen, um die Luftfahrt auf einen mit dem 1,5-Grad-Ziel vereinbaren Pfad zu halten [3].\u00a0<\/span><\/p>\n<p><strong><span style=\"text-decoration: underline;\">Anmerkungen f\u00fcr die Redaktion<\/span>:\u00a0<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">[1] Umfasst Unternehmen, die im Travel Smart Ranking aufgef\u00fchrt sind, deren tats\u00e4chlichen oder gesch\u00e4tzten Flugemissionen im Jahr 2019 zwischen 50.000 und 350.000 Tonnen CO2 lagen und die \u00fcber vergleichbare Daten f\u00fcr 2019 und 2024 verf\u00fcgen. Dies sind einige der gr\u00f6\u00dften Flugreisenden unter den Unternehmen in Deutschland.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">[2] <\/span><span style=\"font-weight: 400;\">Die neun deutschen Unternehmen wurden anhand der Daten aus ihren Nachhaltigkeitsberichten f\u00fcr das Jahr 2024 analysiert. Dank der europ\u00e4ischen Richtlinie zur Nachhaltigkeitsberichterstattung von Unternehmen (<\/span><a href=\"http:\/\/travelsmartcampaign.org\/policy-developments\/corporate-sustainability-reporting-directive-csrd\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">CSRD<\/span><\/a><span style=\"font-weight: 400;\">) ver\u00f6ffentlichen viele Unternehmen nun die Emissionen ihrer Gesch\u00e4ftsreisen in ihren Jahresberichten, sodass diese bewertet werden k\u00f6nnen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">[3] Im Jahr 2024 hat sich der europ\u00e4ische Luftverkehr laut einer <\/span><a href=\"https:\/\/www.transportenvironment.org\/te-france\/articles\/laviation-europeenne-emet-presque-autant-de-co2-quavant-le-covid\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Analyse<\/span><\/a><span style=\"font-weight: 400;\"> von T&amp;E fast vollst\u00e4ndig auf das Niveau vor COVID erholt und erreichte 96 Prozent der Flugzahlen von 2019 und 98 Prozent der CO2-Emissionen. Ohne die Reduzierung der Gesch\u00e4ftsfl\u00fcge w\u00e4re dieser Anstieg noch gr\u00f6\u00dfer ausgefallen.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L'analyse permet de r\u00e9duire durablement les \u00e9missions de gaz \u00e0 effet de serre de 40 % par rapport \u00e0 2019. Les entreprises les plus performantes sont SAP et Allianz : elles ont pu r\u00e9duire leurs \u00e9missions de plus de moiti\u00e9. <\/p>","protected":false},"featured_media":18998,"template":"","topic":[199,96,205,191,190,203,221,165],"visibility":[],"post-country":[32],"language":[39],"category-post-type":[242],"class_list":["post-18994","library","type-library","status-publish","has-post-thumbnail","hentry","topic-air-travel","topic-business-travel","topic-consultancy-sector","topic-corporate-reporting","topic-emission-tracker","topic-emissions-reduction","topic-pharmaceutical-sector","topic-rail","post-country-germany","language-german","category-post-type-analysis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gesch\u00e4ftsreisen: Emissionen von neun gro\u00dfen deutschen Unternehmen um 40 Prozent im Vergleich zu 2019 gesunken - Travel Smart Campaign<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelsmartcampaign.org\/fr\/bibliotheque\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gesch\u00e4ftsreisen: Emissionen von neun gro\u00dfen deutschen Unternehmen um 40 Prozent im Vergleich zu 2019 gesunken - Travel Smart Campaign\" \/>\n<meta property=\"og:description\" content=\"Die Analyse ergibt eine durchschnittliche Reduzierung der gesamten Reiseemissionen um 40 Prozent im Vergleich zu 2019. F\u00fchrende Unternehmen sind SAP und Allianz: Sie konnten ihre Emissionen mehr als halbieren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelsmartcampaign.org\/fr\/bibliotheque\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\/\" \/>\n<meta property=\"og:site_name\" content=\"Travel Smart Campaign\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T13:06:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/allianz-arena-322869_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\\\/\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\\\/\",\"name\":\"Gesch\u00e4ftsreisen: Emissionen von neun gro\u00dfen deutschen Unternehmen um 40 Prozent im Vergleich zu 2019 gesunken - Travel Smart Campaign\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/allianz-arena-322869_1280.jpg\",\"datePublished\":\"2025-10-26T23:01:28+00:00\",\"dateModified\":\"2025-11-05T13:06:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\\\/#primaryimage\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/allianz-arena-322869_1280.jpg\",\"contentUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/allianz-arena-322869_1280.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/library\\\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesch\u00e4ftsreisen: Emissionen von neun gro\u00dfen deutschen Unternehmen um 40 Prozent im Vergleich zu 2019 gesunken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#website\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\",\"name\":\"Travel Smart\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/travelsmartcampaign.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#organization\",\"name\":\"Travel Smart\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/travel-smart-min.jpeg\",\"contentUrl\":\"https:\\\/\\\/travelsmartcampaign.org\\\/wp-content\\\/uploads\\\/travel-smart-min.jpeg\",\"width\":1200,\"height\":690,\"caption\":\"Travel Smart\"},\"image\":{\"@id\":\"https:\\\/\\\/travelsmartcampaign.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les \u00e9missions de gaz \u00e0 effet de serre : Les \u00e9missions de neuf grandes entreprises allemandes ont \u00e9t\u00e9 r\u00e9duites de 40 % par rapport \u00e0 2019 - Campagne Travel Smart","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelsmartcampaign.org\/fr\/bibliotheque\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\/","og_locale":"fr_FR","og_type":"article","og_title":"Gesch\u00e4ftsreisen: Emissionen von neun gro\u00dfen deutschen Unternehmen um 40 Prozent im Vergleich zu 2019 gesunken - Travel Smart Campaign","og_description":"Die Analyse ergibt eine durchschnittliche Reduzierung der gesamten Reiseemissionen um 40 Prozent im Vergleich zu 2019. F\u00fchrende Unternehmen sind SAP und Allianz: Sie konnten ihre Emissionen mehr als halbieren.","og_url":"https:\/\/travelsmartcampaign.org\/fr\/bibliotheque\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\/","og_site_name":"Travel Smart Campaign","article_modified_time":"2025-11-05T13:06:10+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/allianz-arena-322869_1280.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelsmartcampaign.org\/library\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\/","url":"https:\/\/travelsmartcampaign.org\/library\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\/","name":"Les \u00e9missions de gaz \u00e0 effet de serre : Les \u00e9missions de neuf grandes entreprises allemandes ont \u00e9t\u00e9 r\u00e9duites de 40 % par rapport \u00e0 2019 - Campagne Travel Smart","isPartOf":{"@id":"https:\/\/travelsmartcampaign.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/travelsmartcampaign.org\/library\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\/#primaryimage"},"image":{"@id":"https:\/\/travelsmartcampaign.org\/library\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\/#primaryimage"},"thumbnailUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/allianz-arena-322869_1280.jpg","datePublished":"2025-10-26T23:01:28+00:00","dateModified":"2025-11-05T13:06:10+00:00","breadcrumb":{"@id":"https:\/\/travelsmartcampaign.org\/library\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelsmartcampaign.org\/library\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/travelsmartcampaign.org\/library\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\/#primaryimage","url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/allianz-arena-322869_1280.jpg","contentUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/allianz-arena-322869_1280.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/travelsmartcampaign.org\/library\/geschaftsreisen-emissionen-von-neun-grosen-deutschen-unternehmen-um-40-prozent-im-vergleich-zu-2019-gesunken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/travelsmartcampaign.org\/"},{"@type":"ListItem","position":2,"name":"Gesch\u00e4ftsreisen: Emissionen von neun gro\u00dfen deutschen Unternehmen um 40 Prozent im Vergleich zu 2019 gesunken"}]},{"@type":"WebSite","@id":"https:\/\/travelsmartcampaign.org\/#website","url":"https:\/\/travelsmartcampaign.org\/","name":"Classement","description":"","publisher":{"@id":"https:\/\/travelsmartcampaign.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelsmartcampaign.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/travelsmartcampaign.org\/#organization","name":"Classement","url":"https:\/\/travelsmartcampaign.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/travelsmartcampaign.org\/#\/schema\/logo\/image\/","url":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/travel-smart-min.jpeg","contentUrl":"https:\/\/travelsmartcampaign.org\/wp-content\/uploads\/travel-smart-min.jpeg","width":1200,"height":690,"caption":"Travel Smart"},"image":{"@id":"https:\/\/travelsmartcampaign.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/travelsmartcampaign.org\/fr\/wp-json\/wp\/v2\/library\/18994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelsmartcampaign.org\/fr\/wp-json\/wp\/v2\/library"}],"about":[{"href":"https:\/\/travelsmartcampaign.org\/fr\/wp-json\/wp\/v2\/types\/library"}],"version-history":[{"count":0,"href":"https:\/\/travelsmartcampaign.org\/fr\/wp-json\/wp\/v2\/library\/18994\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/fr\/wp-json\/wp\/v2\/media\/18998"}],"wp:attachment":[{"href":"https:\/\/travelsmartcampaign.org\/fr\/wp-json\/wp\/v2\/media?parent=18994"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/fr\/wp-json\/wp\/v2\/topic?post=18994"},{"taxonomy":"visibility","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/fr\/wp-json\/wp\/v2\/visibility?post=18994"},{"taxonomy":"post-country","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/fr\/wp-json\/wp\/v2\/post-country?post=18994"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/fr\/wp-json\/wp\/v2\/language?post=18994"},{"taxonomy":"category-post-type","embeddable":true,"href":"https:\/\/travelsmartcampaign.org\/fr\/wp-json\/wp\/v2\/category-post-type?post=18994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}